{"id":13090,"date":"2024-05-23T15:33:54","date_gmt":"2024-05-23T14:33:54","guid":{"rendered":"https:\/\/frequence-sille.org\/newsite\/?p=13090"},"modified":"2024-05-24T10:11:59","modified_gmt":"2024-05-24T09:11:59","slug":"emission-des-collegiens-zack-et-ses-potosn2","status":"publish","type":"post","link":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/","title":{"rendered":"Emission des coll\u00e9giens \u00ab\u00a0Zack et ses potos\u00a0\u00bbn\u00b02"},"content":{"rendered":"\n<p>Zack et ses potos sont de retour pour une deuxi\u00e8me \u00e9mission au cours de laquelle ils ont abord\u00e9 divers th\u00e8mes :<br>&#8211; Gabriel a parl\u00e9 de l&rsquo;incident de Tchernobyl, et \u00e9voque son stage \u00e0 la centrale nucl\u00e9aire de Chinon,<br>&#8211; Zack nous parle de Lucas Hauchard youtubeur, alias Squeezie,<br>&#8211; Et M\u00e9d\u00e9ric parle du jeux vid\u00e9o Fortnite.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-hearthis-at wp-block-embed-hearthis-at\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Zack et ses potos n\u00b02\" scrolling=\"no\" width=\"100%\" height=\"150\" src=\"https:\/\/hearthis.at\/embed\/11115964\/transparent\/?style=2&#038;block_size=2&#038;block_space=2&#038;background=1#?secret=9CM7iDjM3R\" data-secret=\"9CM7iDjM3R\" frameborder=\"0\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Zack et ses potos sont de retour pour une deuxi\u00e8me \u00e9mission au cours de laquelle ils ont abord\u00e9 divers th\u00e8mes :&#8211; Gabriel a parl\u00e9 de l&rsquo;incident de Tchernobyl, et \u00e9voque&hellip;<\/p>\n","protected":false},"author":1,"featured_media":13091,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-13090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeunesse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emission des coll\u00e9giens &quot;Zack et ses potos&quot;n\u00b02 - Fr\u00e9quence Sill\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emission des coll\u00e9giens &quot;Zack et ses potos&quot;n\u00b02 - Fr\u00e9quence Sill\u00e9\" \/>\n<meta property=\"og:description\" content=\"Zack et ses potos sont de retour pour une deuxi\u00e8me \u00e9mission au cours de laquelle ils ont abord\u00e9 divers th\u00e8mes :&#8211; Gabriel a parl\u00e9 de l&rsquo;incident de Tchernobyl, et \u00e9voque&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frequencesille979fm\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T14:33:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-24T09:11:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/05\/IMG_20240522_105806-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freqsille979\" \/>\n<meta name=\"twitter:site\" content=\"@freqsille979\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/\"},\"author\":{\"name\":\"Fr\u00e9quence Sill\u00e9\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/person\\\/b2ef2baba58f9c81a066ca894f156fc5\"},\"headline\":\"Emission des coll\u00e9giens \u00ab\u00a0Zack et ses potos\u00a0\u00bbn\u00b02\",\"datePublished\":\"2024-05-23T14:33:54+00:00\",\"dateModified\":\"2024-05-24T09:11:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/\"},\"wordCount\":76,\"publisher\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20240522_105806-scaled.jpg\",\"articleSection\":[\"Jeunesse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/\",\"name\":\"Emission des coll\u00e9giens \\\"Zack et ses potos\\\"n\u00b02 - Fr\u00e9quence Sill\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20240522_105806-scaled.jpg\",\"datePublished\":\"2024-05-23T14:33:54+00:00\",\"dateModified\":\"2024-05-24T09:11:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20240522_105806-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/IMG_20240522_105806-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/05\\\/23\\\/emission-des-collegiens-zack-et-ses-potosn2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emission des coll\u00e9giens &#8220;Zack et ses potos&#8221;n\u00b02\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#website\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"description\":\"Bien plus qu&#039;une radio...votre radio !\",\"publisher\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO_979_NOIR.png\",\"contentUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO_979_NOIR.png\",\"width\":7680,\"height\":4320,\"caption\":\"Fr\u00e9quence Sill\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/frequencesille979fm\",\"https:\\\/\\\/x.com\\\/freqsille979\",\"https:\\\/\\\/www.instagram.com\\\/frequencesille\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/person\\\/b2ef2baba58f9c81a066ca894f156fc5\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"caption\":\"Fr\u00e9quence Sill\u00e9\"},\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/author\\\/frequenc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emission des coll\u00e9giens \"Zack et ses potos\"n\u00b02 - Fr\u00e9quence Sill\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/","og_locale":"fr_FR","og_type":"article","og_title":"Emission des coll\u00e9giens \"Zack et ses potos\"n\u00b02 - Fr\u00e9quence Sill\u00e9","og_description":"Zack et ses potos sont de retour pour une deuxi\u00e8me \u00e9mission au cours de laquelle ils ont abord\u00e9 divers th\u00e8mes :&#8211; Gabriel a parl\u00e9 de l&rsquo;incident de Tchernobyl, et \u00e9voque&hellip;","og_url":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/","og_site_name":"Fr\u00e9quence Sill\u00e9","article_publisher":"https:\/\/www.facebook.com\/frequencesille979fm","article_published_time":"2024-05-23T14:33:54+00:00","article_modified_time":"2024-05-24T09:11:59+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/05\/IMG_20240522_105806-scaled.jpg","type":"image\/jpeg"}],"author":"Fr\u00e9quence Sill\u00e9","twitter_card":"summary_large_image","twitter_creator":"@freqsille979","twitter_site":"@freqsille979","twitter_misc":{"\u00c9crit par":"Fr\u00e9quence Sill\u00e9","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#article","isPartOf":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/"},"author":{"name":"Fr\u00e9quence Sill\u00e9","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/person\/b2ef2baba58f9c81a066ca894f156fc5"},"headline":"Emission des coll\u00e9giens \u00ab\u00a0Zack et ses potos\u00a0\u00bbn\u00b02","datePublished":"2024-05-23T14:33:54+00:00","dateModified":"2024-05-24T09:11:59+00:00","mainEntityOfPage":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/"},"wordCount":76,"publisher":{"@id":"https:\/\/frequence-sille.org\/newsite\/#organization"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#primaryimage"},"thumbnailUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/05\/IMG_20240522_105806-scaled.jpg","articleSection":["Jeunesse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/","url":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/","name":"Emission des coll\u00e9giens \"Zack et ses potos\"n\u00b02 - Fr\u00e9quence Sill\u00e9","isPartOf":{"@id":"https:\/\/frequence-sille.org\/newsite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#primaryimage"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#primaryimage"},"thumbnailUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/05\/IMG_20240522_105806-scaled.jpg","datePublished":"2024-05-23T14:33:54+00:00","dateModified":"2024-05-24T09:11:59+00:00","breadcrumb":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#primaryimage","url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/05\/IMG_20240522_105806-scaled.jpg","contentUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/05\/IMG_20240522_105806-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/05\/23\/emission-des-collegiens-zack-et-ses-potosn2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/frequence-sille.org\/newsite\/"},{"@type":"ListItem","position":2,"name":"Emission des coll\u00e9giens &#8220;Zack et ses potos&#8221;n\u00b02"}]},{"@type":"WebSite","@id":"https:\/\/frequence-sille.org\/newsite\/#website","url":"https:\/\/frequence-sille.org\/newsite\/","name":"Fr\u00e9quence Sill\u00e9","description":"Bien plus qu&#039;une radio...votre radio !","publisher":{"@id":"https:\/\/frequence-sille.org\/newsite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frequence-sille.org\/newsite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/frequence-sille.org\/newsite\/#organization","name":"Fr\u00e9quence Sill\u00e9","url":"https:\/\/frequence-sille.org\/newsite\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/logo\/image\/","url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2023\/07\/LOGO_979_NOIR.png","contentUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2023\/07\/LOGO_979_NOIR.png","width":7680,"height":4320,"caption":"Fr\u00e9quence Sill\u00e9"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/frequencesille979fm","https:\/\/x.com\/freqsille979","https:\/\/www.instagram.com\/frequencesille\/"]},{"@type":"Person","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/person\/b2ef2baba58f9c81a066ca894f156fc5","name":"Fr\u00e9quence Sill\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","caption":"Fr\u00e9quence Sill\u00e9"},"url":"https:\/\/frequence-sille.org\/newsite\/author\/frequenc\/"}]}},"_links":{"self":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/13090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/comments?post=13090"}],"version-history":[{"count":2,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/13090\/revisions"}],"predecessor-version":[{"id":13096,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/13090\/revisions\/13096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/media\/13091"}],"wp:attachment":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/media?parent=13090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/categories?post=13090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/tags?post=13090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}