{"id":13435,"date":"2024-06-27T16:03:52","date_gmt":"2024-06-27T15:03:52","guid":{"rendered":"https:\/\/frequence-sille.org\/newsite\/?p=13435"},"modified":"2024-06-27T16:03:53","modified_gmt":"2024-06-27T15:03:53","slug":"emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes","status":"publish","type":"post","link":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/","title":{"rendered":"Emission avec les \u00e9l\u00e8ves de l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 &#8211; RPI Rouess\u00e9-Parennes."},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-hearthis-at wp-block-embed-hearthis-at\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Emission Rouess\u00e9-Vass\u00e9 -RPI \u00e9cole primaire.\" scrolling=\"no\" width=\"100%\" height=\"150\" src=\"https:\/\/hearthis.at\/embed\/11198993\/transparent\/?style=2&#038;block_size=2&#038;block_space=2&#038;background=1#?secret=tmkWeBq5zF\" data-secret=\"tmkWeBq5zF\" frameborder=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Le lundi 24 juin, William, Nicolas et Juliette (stagiaire de seconde) se sont rendus \u00e0 l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 pour r\u00e9aliser en direct une \u00e9mission apr\u00e8s une pr\u00e9paration sur toute la journ\u00e9e. Les th\u00e8mes sont choisis par les \u00e9l\u00e8ves ainsi que les musiques d&rsquo;accompagnement. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le lundi 24 juin, William, Nicolas et Juliette (stagiaire de seconde) se sont rendus \u00e0 l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 pour r\u00e9aliser en direct une \u00e9mission apr\u00e8s une pr\u00e9paration sur toute&hellip;<\/p>\n","protected":false},"author":1,"featured_media":13436,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-13435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-locale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emission avec les \u00e9l\u00e8ves de l&#039;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 - RPI Rouess\u00e9-Parennes. - Fr\u00e9quence Sill\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emission avec les \u00e9l\u00e8ves de l&#039;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 - RPI Rouess\u00e9-Parennes. - Fr\u00e9quence Sill\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le lundi 24 juin, William, Nicolas et Juliette (stagiaire de seconde) se sont rendus \u00e0 l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 pour r\u00e9aliser en direct une \u00e9mission apr\u00e8s une pr\u00e9paration sur toute&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frequencesille979fm\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T15:03:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-27T15:03:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/06\/image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freqsille979\" \/>\n<meta name=\"twitter:site\" content=\"@freqsille979\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/\"},\"author\":{\"name\":\"Fr\u00e9quence Sill\u00e9\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/person\\\/b2ef2baba58f9c81a066ca894f156fc5\"},\"headline\":\"Emission avec les \u00e9l\u00e8ves de l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 &#8211; RPI Rouess\u00e9-Parennes.\",\"datePublished\":\"2024-06-27T15:03:52+00:00\",\"dateModified\":\"2024-06-27T15:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/\"},\"wordCount\":71,\"publisher\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/image.jpg\",\"articleSection\":[\"Vie locale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/\",\"name\":\"Emission avec les \u00e9l\u00e8ves de l'\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 - RPI Rouess\u00e9-Parennes. - Fr\u00e9quence Sill\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/image.jpg\",\"datePublished\":\"2024-06-27T15:03:52+00:00\",\"dateModified\":\"2024-06-27T15:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/image.jpg\",\"contentUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/image.jpg\",\"width\":1365,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/06\\\/27\\\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emission avec les \u00e9l\u00e8ves de l&#8217;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 &#8211; RPI Rouess\u00e9-Parennes.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#website\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"description\":\"Bien plus qu&#039;une radio...votre radio !\",\"publisher\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO_979_NOIR.png\",\"contentUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO_979_NOIR.png\",\"width\":7680,\"height\":4320,\"caption\":\"Fr\u00e9quence Sill\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/frequencesille979fm\",\"https:\\\/\\\/x.com\\\/freqsille979\",\"https:\\\/\\\/www.instagram.com\\\/frequencesille\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/person\\\/b2ef2baba58f9c81a066ca894f156fc5\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"caption\":\"Fr\u00e9quence Sill\u00e9\"},\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/author\\\/frequenc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emission avec les \u00e9l\u00e8ves de l'\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 - RPI Rouess\u00e9-Parennes. - Fr\u00e9quence Sill\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/","og_locale":"fr_FR","og_type":"article","og_title":"Emission avec les \u00e9l\u00e8ves de l'\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 - RPI Rouess\u00e9-Parennes. - Fr\u00e9quence Sill\u00e9","og_description":"Le lundi 24 juin, William, Nicolas et Juliette (stagiaire de seconde) se sont rendus \u00e0 l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 pour r\u00e9aliser en direct une \u00e9mission apr\u00e8s une pr\u00e9paration sur toute&hellip;","og_url":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/","og_site_name":"Fr\u00e9quence Sill\u00e9","article_publisher":"https:\/\/www.facebook.com\/frequencesille979fm","article_published_time":"2024-06-27T15:03:52+00:00","article_modified_time":"2024-06-27T15:03:53+00:00","og_image":[{"width":1365,"height":1024,"url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/06\/image.jpg","type":"image\/jpeg"}],"author":"Fr\u00e9quence Sill\u00e9","twitter_card":"summary_large_image","twitter_creator":"@freqsille979","twitter_site":"@freqsille979","twitter_misc":{"\u00c9crit par":"Fr\u00e9quence Sill\u00e9","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#article","isPartOf":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/"},"author":{"name":"Fr\u00e9quence Sill\u00e9","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/person\/b2ef2baba58f9c81a066ca894f156fc5"},"headline":"Emission avec les \u00e9l\u00e8ves de l&rsquo;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 &#8211; RPI Rouess\u00e9-Parennes.","datePublished":"2024-06-27T15:03:52+00:00","dateModified":"2024-06-27T15:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/"},"wordCount":71,"publisher":{"@id":"https:\/\/frequence-sille.org\/newsite\/#organization"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#primaryimage"},"thumbnailUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/06\/image.jpg","articleSection":["Vie locale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/","url":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/","name":"Emission avec les \u00e9l\u00e8ves de l'\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 - RPI Rouess\u00e9-Parennes. - Fr\u00e9quence Sill\u00e9","isPartOf":{"@id":"https:\/\/frequence-sille.org\/newsite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#primaryimage"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#primaryimage"},"thumbnailUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/06\/image.jpg","datePublished":"2024-06-27T15:03:52+00:00","dateModified":"2024-06-27T15:03:53+00:00","breadcrumb":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#primaryimage","url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/06\/image.jpg","contentUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/06\/image.jpg","width":1365,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/06\/27\/emission-avec-les-eleves-de-lecole-primaire-de-rouesse-vasse-rpi-rouesse-parennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/frequence-sille.org\/newsite\/"},{"@type":"ListItem","position":2,"name":"Emission avec les \u00e9l\u00e8ves de l&#8217;\u00e9cole primaire de Rouess\u00e9-Vass\u00e9 &#8211; RPI Rouess\u00e9-Parennes."}]},{"@type":"WebSite","@id":"https:\/\/frequence-sille.org\/newsite\/#website","url":"https:\/\/frequence-sille.org\/newsite\/","name":"Fr\u00e9quence Sill\u00e9","description":"Bien plus qu&#039;une radio...votre radio !","publisher":{"@id":"https:\/\/frequence-sille.org\/newsite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frequence-sille.org\/newsite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/frequence-sille.org\/newsite\/#organization","name":"Fr\u00e9quence Sill\u00e9","url":"https:\/\/frequence-sille.org\/newsite\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/logo\/image\/","url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2023\/07\/LOGO_979_NOIR.png","contentUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2023\/07\/LOGO_979_NOIR.png","width":7680,"height":4320,"caption":"Fr\u00e9quence Sill\u00e9"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/frequencesille979fm","https:\/\/x.com\/freqsille979","https:\/\/www.instagram.com\/frequencesille\/"]},{"@type":"Person","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/person\/b2ef2baba58f9c81a066ca894f156fc5","name":"Fr\u00e9quence Sill\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","caption":"Fr\u00e9quence Sill\u00e9"},"url":"https:\/\/frequence-sille.org\/newsite\/author\/frequenc\/"}]}},"_links":{"self":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/13435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/comments?post=13435"}],"version-history":[{"count":1,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/13435\/revisions"}],"predecessor-version":[{"id":13437,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/13435\/revisions\/13437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/media\/13436"}],"wp:attachment":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/media?parent=13435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/categories?post=13435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/tags?post=13435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}