{"id":14197,"date":"2024-11-08T15:22:34","date_gmt":"2024-11-08T14:22:34","guid":{"rendered":"https:\/\/frequence-sille.org\/newsite\/?p=14197"},"modified":"2024-11-08T15:22:36","modified_gmt":"2024-11-08T14:22:36","slug":"le-courant-passe-entre-enedis-et-la-mairie-de-beaumont","status":"publish","type":"post","link":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/","title":{"rendered":"Le courant passe entre Enedis et la mairie de Beaumont !"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-hearthis-at wp-block-embed-hearthis-at\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Convention Enedis-Mairie de Beaumont\" scrolling=\"no\" width=\"100%\" height=\"150\" src=\"https:\/\/hearthis.at\/embed\/11482134\/transparent\/?style=2&#038;block_size=2&#038;block_space=2&#038;background=1#?secret=MrxNjbbWB9\" data-secret=\"MrxNjbbWB9\" frameborder=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>L\u00e9a Duval, Maire de Beaumont sur Sarthe et Dominique Chenu, d\u00e9l\u00e9gu\u00e9 territorial d\u2019Enedis en Sarthe, on sign\u00e9 ensemble une convention \u00ab\u00a0Petites Villes de Demain\u00a0\u00bb. Cette convention a pour but d\u2019accompagner la ville sur ses projets de r\u00e9duction de la consommation \u00e9nerg\u00e9tique de ses b\u00e2timents communaux, mais pas que&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00e9a Duval, Maire de Beaumont sur Sarthe et Dominique Chenu, d\u00e9l\u00e9gu\u00e9 territorial d\u2019Enedis en Sarthe, on sign\u00e9 ensemble une convention \u00ab\u00a0Petites Villes de Demain\u00a0\u00bb. Cette convention a pour but d\u2019accompagner&hellip;<\/p>\n","protected":false},"author":1,"featured_media":14198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-14197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-locale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le courant passe entre Enedis et la mairie de Beaumont ! - Fr\u00e9quence Sill\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le courant passe entre Enedis et la mairie de Beaumont ! - Fr\u00e9quence Sill\u00e9\" \/>\n<meta property=\"og:description\" content=\"L\u00e9a Duval, Maire de Beaumont sur Sarthe et Dominique Chenu, d\u00e9l\u00e9gu\u00e9 territorial d\u2019Enedis en Sarthe, on sign\u00e9 ensemble une convention \u00ab\u00a0Petites Villes de Demain\u00a0\u00bb. Cette convention a pour but d\u2019accompagner&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/\" \/>\n<meta property=\"og:site_name\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frequencesille979fm\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T14:22:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T14:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/11\/20241025_120227-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freqsille979\" \/>\n<meta name=\"twitter:site\" content=\"@freqsille979\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fr\u00e9quence Sill\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/\"},\"author\":{\"name\":\"Fr\u00e9quence Sill\u00e9\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/person\\\/b2ef2baba58f9c81a066ca894f156fc5\"},\"headline\":\"Le courant passe entre Enedis et la mairie de Beaumont !\",\"datePublished\":\"2024-11-08T14:22:34+00:00\",\"dateModified\":\"2024-11-08T14:22:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/\"},\"wordCount\":71,\"publisher\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241025_120227-1-scaled.jpg\",\"articleSection\":[\"Vie locale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/\",\"name\":\"Le courant passe entre Enedis et la mairie de Beaumont ! - Fr\u00e9quence Sill\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241025_120227-1-scaled.jpg\",\"datePublished\":\"2024-11-08T14:22:34+00:00\",\"dateModified\":\"2024-11-08T14:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241025_120227-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20241025_120227-1-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/2024\\\/11\\\/08\\\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le courant passe entre Enedis et la mairie de Beaumont !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#website\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"description\":\"Bien plus qu&#039;une radio...votre radio !\",\"publisher\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#organization\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO_979_NOIR.png\",\"contentUrl\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO_979_NOIR.png\",\"width\":7680,\"height\":4320,\"caption\":\"Fr\u00e9quence Sill\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/frequencesille979fm\",\"https:\\\/\\\/x.com\\\/freqsille979\",\"https:\\\/\\\/www.instagram.com\\\/frequencesille\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/#\\\/schema\\\/person\\\/b2ef2baba58f9c81a066ca894f156fc5\",\"name\":\"Fr\u00e9quence Sill\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g\",\"caption\":\"Fr\u00e9quence Sill\u00e9\"},\"url\":\"https:\\\/\\\/frequence-sille.org\\\/newsite\\\/author\\\/frequenc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le courant passe entre Enedis et la mairie de Beaumont ! - Fr\u00e9quence Sill\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/","og_locale":"fr_FR","og_type":"article","og_title":"Le courant passe entre Enedis et la mairie de Beaumont ! - Fr\u00e9quence Sill\u00e9","og_description":"L\u00e9a Duval, Maire de Beaumont sur Sarthe et Dominique Chenu, d\u00e9l\u00e9gu\u00e9 territorial d\u2019Enedis en Sarthe, on sign\u00e9 ensemble une convention \u00ab\u00a0Petites Villes de Demain\u00a0\u00bb. Cette convention a pour but d\u2019accompagner&hellip;","og_url":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/","og_site_name":"Fr\u00e9quence Sill\u00e9","article_publisher":"https:\/\/www.facebook.com\/frequencesille979fm","article_published_time":"2024-11-08T14:22:34+00:00","article_modified_time":"2024-11-08T14:22:36+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/11\/20241025_120227-1-scaled.jpg","type":"image\/jpeg"}],"author":"Fr\u00e9quence Sill\u00e9","twitter_card":"summary_large_image","twitter_creator":"@freqsille979","twitter_site":"@freqsille979","twitter_misc":{"\u00c9crit par":"Fr\u00e9quence Sill\u00e9","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#article","isPartOf":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/"},"author":{"name":"Fr\u00e9quence Sill\u00e9","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/person\/b2ef2baba58f9c81a066ca894f156fc5"},"headline":"Le courant passe entre Enedis et la mairie de Beaumont !","datePublished":"2024-11-08T14:22:34+00:00","dateModified":"2024-11-08T14:22:36+00:00","mainEntityOfPage":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/"},"wordCount":71,"publisher":{"@id":"https:\/\/frequence-sille.org\/newsite\/#organization"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#primaryimage"},"thumbnailUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/11\/20241025_120227-1-scaled.jpg","articleSection":["Vie locale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/","url":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/","name":"Le courant passe entre Enedis et la mairie de Beaumont ! - Fr\u00e9quence Sill\u00e9","isPartOf":{"@id":"https:\/\/frequence-sille.org\/newsite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#primaryimage"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#primaryimage"},"thumbnailUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/11\/20241025_120227-1-scaled.jpg","datePublished":"2024-11-08T14:22:34+00:00","dateModified":"2024-11-08T14:22:36+00:00","breadcrumb":{"@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#primaryimage","url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/11\/20241025_120227-1-scaled.jpg","contentUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2024\/11\/20241025_120227-1-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/frequence-sille.org\/newsite\/2024\/11\/08\/le-courant-passe-entre-enedis-et-la-mairie-de-beaumont\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/frequence-sille.org\/newsite\/"},{"@type":"ListItem","position":2,"name":"Le courant passe entre Enedis et la mairie de Beaumont !"}]},{"@type":"WebSite","@id":"https:\/\/frequence-sille.org\/newsite\/#website","url":"https:\/\/frequence-sille.org\/newsite\/","name":"Fr\u00e9quence Sill\u00e9","description":"Bien plus qu&#039;une radio...votre radio !","publisher":{"@id":"https:\/\/frequence-sille.org\/newsite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frequence-sille.org\/newsite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/frequence-sille.org\/newsite\/#organization","name":"Fr\u00e9quence Sill\u00e9","url":"https:\/\/frequence-sille.org\/newsite\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/logo\/image\/","url":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2023\/07\/LOGO_979_NOIR.png","contentUrl":"https:\/\/frequence-sille.org\/newsite\/wp-content\/uploads\/2023\/07\/LOGO_979_NOIR.png","width":7680,"height":4320,"caption":"Fr\u00e9quence Sill\u00e9"},"image":{"@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/frequencesille979fm","https:\/\/x.com\/freqsille979","https:\/\/www.instagram.com\/frequencesille\/"]},{"@type":"Person","@id":"https:\/\/frequence-sille.org\/newsite\/#\/schema\/person\/b2ef2baba58f9c81a066ca894f156fc5","name":"Fr\u00e9quence Sill\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8edea065a20d07d283ef9c5595da1859244093fbe2c620eb7cb86d4a5cbb52d6?s=96&d=mm&r=g","caption":"Fr\u00e9quence Sill\u00e9"},"url":"https:\/\/frequence-sille.org\/newsite\/author\/frequenc\/"}]}},"_links":{"self":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/14197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/comments?post=14197"}],"version-history":[{"count":1,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/14197\/revisions"}],"predecessor-version":[{"id":14199,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/posts\/14197\/revisions\/14199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/media\/14198"}],"wp:attachment":[{"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/media?parent=14197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/categories?post=14197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frequence-sille.org\/newsite\/wp-json\/wp\/v2\/tags?post=14197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}